{"id":17448,"date":"2026-07-14T10:37:28","date_gmt":"2026-07-14T10:37:28","guid":{"rendered":"https:\/\/larepublicamx.com\/index.php\/2026\/07\/14\/jose-maria-sosa-declarado-culpable-por-la-desaparicion-de-paulina-camargo-tras-casi-11-anos-de-proceso\/"},"modified":"2026-07-14T16:37:30","modified_gmt":"2026-07-14T16:37:30","slug":"jose-maria-sosa-declarado-culpable-por-la-desaparicion-de-paulina-camargo-tras-casi-11-anos-de-proceso","status":"publish","type":"post","link":"https:\/\/larepublicamx.com\/index.php\/2026\/07\/14\/jose-maria-sosa-declarado-culpable-por-la-desaparicion-de-paulina-camargo-tras-casi-11-anos-de-proceso\/","title":{"rendered":"Jos\u00e9 Mar\u00eda Sosa declarado culpable por la desaparici\u00f3n de Paulina Camargo tras casi 11 a\u00f1os de proceso"},"content":{"rendered":"<p>Despu\u00e9s de m\u00e1s de 18 horas de audiencia de alegatos finales, el Tribunal de Enjuiciamiento del Centro de Justicia Penal de la 11 Sur declar\u00f3 culpable a Jos\u00e9 Mar\u00eda Sosa por la desaparici\u00f3n de Paulina Camargo Lim\u00f3n, ocurrida el 25 de agosto de 2015. En ese momento, Paulina ten\u00eda 19 a\u00f1os y se encontraba con cuatro meses de embarazo.<\/p>\n<p>Este fallo representa un primer acto de justicia para la familia Camargo Lim\u00f3n, que durante casi 11 a\u00f1os ha buscado incansablemente esclarecer el paradero de Paulina y exigir que el responsable sea sancionado.<\/p>\n<p>La audiencia de individualizaci\u00f3n de sanciones se llevar\u00e1 a cabo el pr\u00f3ximo 17 de julio a las 13 horas, donde el tribunal determinar\u00e1 la pena de prisi\u00f3n que deber\u00e1 cumplir Jos\u00e9 Mar\u00eda Sosa, as\u00ed como la reparaci\u00f3n integral del da\u00f1o.<\/p>\n<p>Al concluir la audiencia, Roc\u00edo Lim\u00f3n, madre de Paulina, agradeci\u00f3 el apoyo de familiares y amigos que permanecieron en un plant\u00f3n frente al Centro de Justicia para acompa\u00f1ar el desarrollo del proceso judicial. \u201cLo que \u00e9l hizo, lo que le hizo a Paulina no estuvo bien; adem\u00e1s, el beb\u00e9 era su hijo. Gracias a todos por estar aqu\u00ed\u201d, expres\u00f3.<\/p>\n<p>El proceso judicial ha sido largo y complejo. Inicialmente, la Fiscal\u00eda General del Estado imput\u00f3 a Jos\u00e9 Mar\u00eda Sosa, entonces expareja sentimental de Paulina, por homicidio doloso y aborto. En febrero de 2019 fue declarado culpable, y en 2022 un juez ratific\u00f3 la sentencia con base en pruebas testimoniales, videograbaciones y una declaraci\u00f3n del propio acusado, quien reconoci\u00f3 haber golpeado a Paulina y deshacerse de su cuerpo.<\/p>\n<p>No obstante, en abril de 2024 un tribunal federal anul\u00f3 esa sentencia al considerar que no exist\u00eda el cuerpo del delito, dado que los restos de la joven nunca fueron localizados.<\/p>\n<p>Paralelamente, desde 2017 la familia promovi\u00f3 una nueva causa penal por desaparici\u00f3n cometida por particulares, amparada en la Ley General en Materia de Desaparici\u00f3n Forzada de Personas y Desaparici\u00f3n Cometida por Particulares. Diversos recursos de apelaci\u00f3n y juicios de amparo retrasaron el inicio del juicio oral hasta febrero de 2026.<\/p>\n<p>Durante cerca de seis meses, los padres y familiares de Paulina enfrentaron nuevamente al acusado en cada audiencia, donde rindieron sus testimonios. Con el fallo emitido este martes 14 de julio de 2026, el tribunal reconoci\u00f3 la responsabilidad penal de Jos\u00e9 Mar\u00eda Sosa por la desaparici\u00f3n de Paulina Camargo.<\/p>\n<p>El caso de Paulina Camargo comenz\u00f3 en 2013, cuando conoci\u00f3 a Jos\u00e9 Mar\u00eda Sosa. Lo que inici\u00f3 como una amistad se convirti\u00f3 en una relaci\u00f3n sentimental que nunca cont\u00f3 con la aprobaci\u00f3n de Roc\u00edo Lim\u00f3n, madre de la joven, quien desde un principio desconfiaba del acusado.<\/p>\n<p>En mayo de 2015, Paulina descubri\u00f3 que estaba embarazada. La noticia no fue bien recibida por Sosa, quien abandon\u00f3 temporalmente el estado argumentando que necesitaba tiempo para pensar. Dos meses despu\u00e9s regres\u00f3 y asegur\u00f3 estar listo para hablar sobre la relaci\u00f3n y el embarazo.<\/p>\n<p>El 25 de agosto de 2015, Paulina acudi\u00f3 a una consulta ginecol\u00f3gica en una cl\u00ednica de la colonia Jardines de San Manuel para conocer el sexo de su beb\u00e9. Al concluir la cita, a la que asistieron sus padres y Jos\u00e9 Mar\u00eda Sosa, este le pidi\u00f3 conversar en privado. Aunque inicialmente se mostr\u00f3 renuente, Paulina acept\u00f3 reunirse con \u00e9l en un caf\u00e9 de Plaza del Sol.<\/p>\n<p>Seg\u00fan la investigaci\u00f3n, durante ese encuentro Sosa la convenci\u00f3 de trasladarse a su departamento en la Unidad Habitacional La Margarita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de m\u00e1s de 18 horas de audiencia de alegatos finales, el Tribunal de Enjuiciamiento del Centro de Justicia Penal de la 11 Sur declar\u00f3 culpable a Jos\u00e9 Mar\u00eda Sosa por la desaparici\u00f3n de Paulina Camargo Lim\u00f3n, ocurrida el 25 de agosto de 2015. En ese momento, Paulina ten\u00eda 19 a\u00f1os y se encontraba con&#8230;<\/p>\n","protected":false},"author":1,"featured_media":17447,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-17448","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local"],"_links":{"self":[{"href":"https:\/\/larepublicamx.com\/index.php\/wp-json\/wp\/v2\/posts\/17448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larepublicamx.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larepublicamx.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larepublicamx.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/larepublicamx.com\/index.php\/wp-json\/wp\/v2\/comments?post=17448"}],"version-history":[{"count":1,"href":"https:\/\/larepublicamx.com\/index.php\/wp-json\/wp\/v2\/posts\/17448\/revisions"}],"predecessor-version":[{"id":17449,"href":"https:\/\/larepublicamx.com\/index.php\/wp-json\/wp\/v2\/posts\/17448\/revisions\/17449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larepublicamx.com\/index.php\/wp-json\/wp\/v2\/media\/17447"}],"wp:attachment":[{"href":"https:\/\/larepublicamx.com\/index.php\/wp-json\/wp\/v2\/media?parent=17448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larepublicamx.com\/index.php\/wp-json\/wp\/v2\/categories?post=17448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larepublicamx.com\/index.php\/wp-json\/wp\/v2\/tags?post=17448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}